{"id":7592,"date":"2023-03-20T06:55:36","date_gmt":"2023-03-20T06:55:36","guid":{"rendered":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/product\/roza-half-arch-mirror\/"},"modified":"2023-03-20T13:23:39","modified_gmt":"2023-03-20T13:23:39","slug":"roza-half-arch-mirror","status":"publish","type":"product","link":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/product\/roza-half-arch-mirror\/","title":{"rendered":"Roza Half Arch Mirror"},"content":{"rendered":"<p><meta charset=\"UTF-8\"><\/p>\n<p class=\"p1\">Our Stunning Roza Half Arch Mirror is the perfect mirror to fill a space on top of a console or table<\/p>\n<p class=\"p1\"><span class=\"s1\">Dimension:<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">120cm H x 160cm W<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><meta charset=\"utf-8\"> <span>All our mirrors are made to order, custom sizes available on request<\/span><\/span><\/p>\n<p class=\"p1\">\u00a0Frame Color:<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">\n<span class=\"s2\"><\/span><span class=\"s1\">Frameless Design<\/span>\n<\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\">Material <\/span><\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">\n<span class=\"s2\"><\/span><span class=\"s1\">MDF solid frame<\/span>\n<\/li>\n<li class=\"li1\">\n<span class=\"s2\"><\/span><span class=\"s1\">Made in UAE<\/span>\n<\/li>\n<\/ul>\n<p class=\"p1\">\u00a0<\/p>\n<p class=\"p1\">Lead Time 7 days from date of order.\u00a0<\/p>\n<p class=\"p1\">Made in the UAE.\u00a0<\/p>\n<p class=\"p1\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Our Stunning Roza Half Arch Mirror is the perfect mirror to fill a space on top of a console or table Dimension: 120cm H x 160cm W All our mirrors are made to order, custom sizes available on request \u00a0Frame Color: Frameless Design Material MDF solid frame Made in UAE \u00a0 Lead Time 7 days [&hellip;]<\/p>\n","protected":false},"featured_media":7591,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[88],"product_tag":[],"_links":{"self":[{"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/product\/7592"}],"collection":[{"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/comments?post=7592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/media\/7591"}],"wp:attachment":[{"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/media?parent=7592"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/product_cat?post=7592"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brassy.in\/palmlivingdevelopment\/index.php\/wp-json\/wp\/v2\/product_tag?post=7592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}